{"id":721,"date":"2024-10-15T09:41:50","date_gmt":"2024-10-15T16:41:50","guid":{"rendered":"https:\/\/places.sca-caid.org\/caid\/?page_id=721"},"modified":"2026-07-04T13:43:00","modified_gmt":"2026-07-04T20:43:00","slug":"arts-sciences","status":"publish","type":"page","link":"https:\/\/places.sca-caid.org\/caid\/arts-sciences\/","title":{"rendered":"Arts &amp; Sciences"},"content":{"rendered":"<div class=\"et_pb_section_0 et_pb_section et_section_regular et_block_section\">\n<div class=\"et_pb_row_0 et_pb_row et_block_row\">\n<div class=\"et_pb_column_0 et_pb_column et_pb_column_2_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_0 et_pb_text et_pb_bg_layout_dark et_animated et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h1>Arts &amp; Sciences of Caid<\/h1>\n<\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_1 et_pb_column et_pb_column_1_3 et-last-child et_block_column et_pb_column_empty et_pb_css_mix_blend_mode_passthrough\"><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_section_1 et_pb_section et_section_regular et_block_section\">\n<div class=\"et_pb_row_1 et_pb_row et_block_row\">\n<div class=\"et_pb_column_2 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_1 et_pb_text et_pb_bg_layout_dark et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h1 style=\"text-align: center\">A&amp;S Resources<\/h1>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_2 et_pb_row et_block_row\">\n<div class=\"et_pb_column_3 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_filterable_portfolio_0 et_pb_filterable_portfolio et_pb_bg_layout_dark et_pb_text_align_center et_pb_portfolio et_pb_module\" data-posts-number=\"10\"><div class=\"et_pb_portfolio_filters clearfix\"><ul class=\"clearfix\"><li class=\"et_pb_portfolio_filter et_pb_portfolio_filter_all\"><a href=\"#\" class=\"active\" data-category-slug=\"all\">All<\/a><\/li><li class=\"et_pb_portfolio_filter\"><a href=\"#\" data-category-slug=\"as\">A&amp;S<\/a><\/li><li class=\"et_pb_portfolio_filter\"><a href=\"#\" data-category-slug=\"misc\">Misc<\/a><\/li><\/ul><\/div><div class=\"et_pb_portfolio_items_wrapper clearfix\"><div class=\"et_pb_portfolio_items et_pb_posts et_grid_module\"><div class=\"et_pb_filterable_portfolio_item_0_0 post-123172 project type-project status-publish hentry project_category-investigation-faqs project_category-misc project_category-seneschal-handbooks project_category-seneschal-investigations project_category-seneschal-processes project_category-society-seneschal et_pb_portfolio_item project_category_investigation-faqs project_category_misc project_category_seneschal-handbooks project_category_seneschal-investigations project_category_seneschal-processes project_category_society-seneschal\" id=\"123172\"><h2 class=\"et_pb_module_header\"><a href=\"https:\/\/places.sca-caid.org\/caid\/project\/conduct-behavior-in-the-sca\/\" title=\"Conduct &amp; Behavior in the SCA\">Conduct &amp; Behavior in the SCA<\/a><\/h2><\/div><div class=\"et_pb_filterable_portfolio_item_0_1 post-2102 project type-project status-publish hentry project_category-as et_pb_portfolio_item project_category_as\" id=\"2102\"><h2 class=\"et_pb_module_header\"><a href=\"https:\/\/places.sca-caid.org\/caid\/project\/general-marshal-forms-2\/\" title=\"General A&amp;S Documents and Websites\">General A&amp;S Documents and Websites<\/a><\/h2><\/div><div class=\"et_pb_filterable_portfolio_item_0_2 post-2096 project type-project status-publish hentry project_category-misc et_pb_portfolio_item project_category_misc\" id=\"2096\"><h2 class=\"et_pb_module_header\"><a href=\"https:\/\/places.sca-caid.org\/caid\/project\/sca-warrant-of-appointment-to-office\/\" title=\"SCA Warrant of Appointment to Office\">SCA Warrant of Appointment to Office<\/a><\/h2><\/div><div class=\"et_pb_filterable_portfolio_item_0_3 post-2092 project type-project status-publish hentry project_category-misc et_pb_portfolio_item project_category_misc\" id=\"2092\"><h2 class=\"et_pb_module_header\"><a href=\"https:\/\/places.sca-caid.org\/caid\/project\/caidian-agreement-to-serve-form\/\" title=\"Caidian Agreement to Serve Form\">Caidian Agreement to Serve Form<\/a><\/h2><\/div><div class=\"et_pb_filterable_portfolio_item_0_4 post-2090 project type-project status-publish hentry project_category-as et_pb_portfolio_item project_category_as\" id=\"2090\"><h2 class=\"et_pb_module_header\"><a href=\"https:\/\/places.sca-caid.org\/caid\/project\/caidian-arts-sciences-handbook-legacy\/\" title=\"Caidian Arts &#038; Sciences Handbook (legacy)\">Caidian Arts &#038; Sciences Handbook (legacy)<\/a><\/h2><\/div><\/div><\/div><div class=\"et_pb_portofolio_pagination clearfix\"><\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_3 et_pb_row et_pb_gutters1 et_block_row et_animated\">\n<div class=\"et_pb_column_4 et_pb_column et_pb_column_1_2 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_2 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h3 style=\"text-align: center\"><strong>Quarterly Report<\/strong><\/h3>\n<\/div><\/div>\n\n<div class=\"et_pb_text_3 et_pb_text et_pb_bg_layout_dark et_animated et_clickable et_pb_module et_block_module et_pb_text_align_center\"><div class=\"et_pb_text_inner\"><p><span><strong>Reports due:\u00a0 <\/strong><\/span><span><strong>March 1st;\u00a0 <\/strong><\/span><span><strong>June 1st;\u00a0 <\/strong><\/span><span><strong>September 1st;\u00a0 <\/strong><\/span><span><strong>December 1st<\/strong><\/span><\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_0_wrapper\"><a class=\"et_pb_button_0 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module\" href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSdYMNKVDIze2ehr6TeTngZViacqjzKFYDtFYPSg7kkhkB7pAA\/viewform\">Report Here<\/a><\/div>\n<\/div>\n\n<div class=\"et_pb_column_5 et_pb_column et_pb_column_1_2 et-last-child et_block_column et_pb_column_empty et_pb_css_mix_blend_mode_passthrough\"><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_section_2 et_pb_section et_section_regular et_block_section\">\n<div class=\"et_pb_row_4 et_pb_row et_pb_gutters2 et_block_row\">\n<div class=\"et_pb_column_6 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_4 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h2><span class=\"s1\">Kingdom <\/span>Arts &amp; Sciences<\/h2>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_5 et_pb_row et_block_row et_animated\">\n<div class=\"et_pb_column_7 et_pb_column et_pb_column_1_2 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_team_member_0 et_pb_team_member et_pb_team_member_no_image et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_team_member_description\"><h4 class=\"et_pb_module_header\">Avicia de Na Baiona<\/h4><p class=\"et_pb_member_position\">Kingdom Minister of Arts and Sciences<\/p><div class=\"et_pb_team_member_description_content\"><p><a href=\"mailto:arts.officer@sca-caid.org\"><span>arts.officer@sca-caid.org<\/span><\/a><\/p>\n<\/div><\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_8 et_pb_column et_pb_column_1_2 et-last-child et_block_column et_pb_column_empty et_pb_css_mix_blend_mode_passthrough\"><\/div>\n<\/div>\n\n<div class=\"et_pb_row_6 et_pb_row et_pb_gutters2 et_block_row\">\n<div class=\"et_pb_column_9 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_5 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p><strong>Master Valeria Cabrielli<\/strong><br \/><strong><a href=\"mailto:arts.deputy@sca-caid.org\">Deputy Minister of Arts and Sciences<\/a><\/strong><\/p>\n<\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_10 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_6 et_pb_text et_pb_bg_layout_light et_clickable et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><div class=\"name_heading\"><strong>Baroness Finella Harper<\/strong><\/div>\n<div class=\"name_heading\"><strong><a href=\"mailto:chancellor@sca-caid.org\">Collegium Chancellor<\/a><\/strong><\/div>\n<\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_11 et_pb_column et_pb_column_1_3 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_7 et_pb_text et_pb_bg_layout_light et_clickable et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><div class=\"name_heading\"><strong>Lady\u00a0\u00c1ine of Phoenix Glade<\/strong><br \/><strong><a href=\"mailto:artsandsciences.steward@gww.sca-caid.org\">GWW Arts &amp; Sciences Steward<\/a><\/strong><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_7 et_pb_row et_pb_row_4col et_pb_gutters2 et_block_row et_block_row_4col\">\n<div class=\"et_pb_column_12 et_pb_column et_pb_column_1_4 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_8 et_pb_text et_pb_bg_layout_light et_clickable et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><div class=\"name_heading\"><span style=\"color: #000000\"><strong>Vacant<\/strong><\/span><\/div>\n<div class=\"name_heading\"><span style=\"color: #3366ff\"><strong>Pentathlon Steward<\/strong><\/span><\/div>\n<\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_13 et_pb_column et_pb_column_1_4 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_9 et_pb_text et_pb_bg_layout_light et_clickable et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><div class=\"name_heading\"><strong><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Baron Sir Philip Williams of Aston&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:6659,&quot;3&quot;:{&quot;1&quot;:0},&quot;4&quot;:{&quot;1&quot;:2,&quot;2&quot;:15987699},&quot;12&quot;:0,&quot;14&quot;:{&quot;1&quot;:2,&quot;2&quot;:0},&quot;15&quot;:&quot;Arial&quot;}\" style=\"color: #000000\">Baron Sir Philip Williams of Aston<\/span><\/strong><br \/><span style=\"color: #3366ff\"><strong>Deputy Minister of Historical Combat Studies<\/strong><\/span><\/div>\n<\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_14 et_pb_column et_pb_column_1_4 et_block_column et_pb_column_empty et_pb_css_mix_blend_mode_passthrough\"><\/div>\n\n<div class=\"et_pb_column_15 et_pb_column et_pb_column_1_4 et-last-child et_block_column et_pb_column_empty et_pb_css_mix_blend_mode_passthrough\"><\/div>\n<\/div>\n\n\n<\/div>\n\n\n\n\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","footnotes":""},"difl_page_category":[],"class_list":["post-721","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/places.sca-caid.org\/caid\/wp-json\/wp\/v2\/pages\/721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/places.sca-caid.org\/caid\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/places.sca-caid.org\/caid\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/places.sca-caid.org\/caid\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/places.sca-caid.org\/caid\/wp-json\/wp\/v2\/comments?post=721"}],"version-history":[{"count":7,"href":"https:\/\/places.sca-caid.org\/caid\/wp-json\/wp\/v2\/pages\/721\/revisions"}],"predecessor-version":[{"id":123818,"href":"https:\/\/places.sca-caid.org\/caid\/wp-json\/wp\/v2\/pages\/721\/revisions\/123818"}],"wp:attachment":[{"href":"https:\/\/places.sca-caid.org\/caid\/wp-json\/wp\/v2\/media?parent=721"}],"wp:term":[{"taxonomy":"difl_page_category","embeddable":true,"href":"https:\/\/places.sca-caid.org\/caid\/wp-json\/wp\/v2\/difl_page_category?post=721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}